{"id":4785,"date":"2018-01-05T22:49:26","date_gmt":"2018-01-05T22:49:26","guid":{"rendered":"https:\/\/alcogal.com\/?p=4785\/"},"modified":"2021-12-03T17:55:30","modified_gmt":"2021-12-03T22:55:30","slug":"alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones","status":"publish","type":"post","link":"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/","title":{"rendered":"Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por la suma de USD320 millones"},"content":{"rendered":"<p class=\"p1\" style=\"text-align: left;\"><span class=\"s1\">Alcogal asesor\u00f3 a Alternegy, S.A.<b> <\/b>en su primera emisi\u00f3n de bonos por un monto de USD320 millones<i>,<\/i><\/span> <span class=\"s1\">suscrito por Banco General, S.A. y Banistmo, S.A., siendo \u00e9sta la emisi\u00f3n <\/span><span class=\"s3\">m\u00e1s grande del a\u00f1o para un emisor corporativo en el mercado de capitales paname\u00f1o. <\/span><span class=\"s1\">La emisi\u00f3n cuenta con garant\u00edas locales e internacionales, \u00e9stas \u00faltimas espec\u00edficamente consistentes en activos localizados en la Rep\u00fablica de Costa Rica. <\/span><\/p>\n<p class=\"p1\" style=\"text-align: left;\"><span class=\"s1\">La transacci\u00f3n concluy\u00f3 en diciembre 2017.<\/span><\/p>\n<p class=\"p1\" style=\"text-align: left;\"><span class=\"s1\">El socio Arturo Gerbaud, junto con el asociado Rafael Marqu\u00ednez, estuvieron a cargo de esta transacci\u00f3n.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por un monto de USD320 millones, suscrito por Banco General, S.A. y Banistmo, S.A., siendo \u00e9sta la emisi\u00f3n m\u00e1s grande del a\u00f1o para un emisor corporativo en el mercado de capitales paname\u00f1o. La emisi\u00f3n cuenta con garant\u00edas locales e internacionales, \u00e9stas \u00faltimas espec\u00edficamente consistentes &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/\"> <span class=\"screen-reader-text\">Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por la suma de USD320 millones<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":12859,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[47],"tags":[],"class_list":["post-4785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-transacciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por la suma de USD320 millones | Alem\u00e1n, Cordero, Galindo &amp; Lee<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por la suma de USD320 millones\" \/>\n<meta property=\"og:description\" content=\"Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por un monto de USD320 millones, suscrito por Banco General, S.A. y Banistmo, S.A., siendo \u00e9sta la emisi\u00f3n m\u00e1s grande del a\u00f1o para un emisor corporativo en el mercado de capitales paname\u00f1o. La emisi\u00f3n cuenta con garant\u00edas locales e internacionales, \u00e9stas \u00faltimas espec\u00edficamente consistentes &hellip; Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por la suma de USD320 millones Leer m\u00e1s &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/\" \/>\n<meta property=\"og:site_name\" content=\"Alem\u00e1n, Cordero, Galindo &amp; Lee\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AlcogalAbogados\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-05T22:49:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-03T22:55:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/alcogal.com\/wp-content\/uploads\/2017\/09\/A.Gerbaud-R.Marquinez.jpg?fit=420%2C300&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alcogal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@alcogalabogados\" \/>\n<meta name=\"twitter:site\" content=\"@alcogalabogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alcogal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\\\/\"},\"author\":{\"name\":\"Alcogal\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#\\\/schema\\\/person\\\/c99b01ea3d22bdf5a226f88b22e8d1d7\"},\"headline\":\"Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por la suma de USD320 millones\",\"datePublished\":\"2018-01-05T22:49:26+00:00\",\"dateModified\":\"2021-12-03T22:55:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\\\/\"},\"wordCount\":119,\"publisher\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/A.Gerbaud-R.Marquinez.jpg\",\"articleSection\":[\"Transacciones\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\\\/\",\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\\\/\",\"name\":\"Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por la suma de USD320 millones | Alem\u00e1n, Cordero, Galindo &amp; Lee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/A.Gerbaud-R.Marquinez.jpg\",\"datePublished\":\"2018-01-05T22:49:26+00:00\",\"dateModified\":\"2021-12-03T22:55:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/A.Gerbaud-R.Marquinez.jpg\",\"contentUrl\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/A.Gerbaud-R.Marquinez.jpg\",\"width\":420,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alcogal.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por la suma de USD320 millones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/\",\"name\":\"Alem\u00e1n Cordero Galindo & Lee\",\"description\":\"Firma de Abogados en Panam\u00e1\",\"publisher\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#organization\"},\"alternateName\":\"Alcogal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alcogal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#organization\",\"name\":\"Aleman, Cordero, Galindo & Lee\",\"alternateName\":\"Alcogal\",\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-alcogal.png\",\"contentUrl\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-alcogal.png\",\"width\":696,\"height\":696,\"caption\":\"Aleman, Cordero, Galindo & Lee\"},\"image\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AlcogalAbogados\\\/\",\"https:\\\/\\\/x.com\\\/alcogalabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/alcogal\\\/\",\"https:\\\/\\\/www.instagram.com\\\/alcogalabogados\\\/\"],\"description\":\"Since our foundation in 1985, we have established ourselves as one of Panama\u2019s most prestigious law firms. We are a full-service firm with a team of lawyers who provide timely and efficient advice in all practice areas\",\"email\":\"contact@alcogal.com\",\"telephone\":\"+507 269-2620\",\"foundingDate\":\"1985-01-01\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#\\\/schema\\\/person\\\/c99b01ea3d22bdf5a226f88b22e8d1d7\",\"name\":\"Alcogal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/438173877dc45e2c5735b6ee45d71a1701c94eb9c1fd1d2501655e3db906ad2a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/438173877dc45e2c5735b6ee45d71a1701c94eb9c1fd1d2501655e3db906ad2a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/438173877dc45e2c5735b6ee45d71a1701c94eb9c1fd1d2501655e3db906ad2a?s=96&d=mm&r=g\",\"caption\":\"Alcogal\"},\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/author\\\/adminmarissa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por la suma de USD320 millones | Alem\u00e1n, Cordero, Galindo &amp; Lee","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/","og_locale":"es_ES","og_type":"article","og_title":"Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por la suma de USD320 millones","og_description":"Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por un monto de USD320 millones, suscrito por Banco General, S.A. y Banistmo, S.A., siendo \u00e9sta la emisi\u00f3n m\u00e1s grande del a\u00f1o para un emisor corporativo en el mercado de capitales paname\u00f1o. La emisi\u00f3n cuenta con garant\u00edas locales e internacionales, \u00e9stas \u00faltimas espec\u00edficamente consistentes &hellip; Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por la suma de USD320 millones Leer m\u00e1s &raquo;","og_url":"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/","og_site_name":"Alem\u00e1n, Cordero, Galindo &amp; Lee","article_publisher":"https:\/\/www.facebook.com\/AlcogalAbogados\/","article_published_time":"2018-01-05T22:49:26+00:00","article_modified_time":"2021-12-03T22:55:30+00:00","og_image":[{"width":420,"height":300,"url":"https:\/\/i0.wp.com\/alcogal.com\/wp-content\/uploads\/2017\/09\/A.Gerbaud-R.Marquinez.jpg?fit=420%2C300&ssl=1","type":"image\/jpeg"}],"author":"Alcogal","twitter_card":"summary_large_image","twitter_creator":"@alcogalabogados","twitter_site":"@alcogalabogados","twitter_misc":{"Escrito por":"Alcogal","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/#article","isPartOf":{"@id":"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/"},"author":{"name":"Alcogal","@id":"https:\/\/alcogal.com\/es\/#\/schema\/person\/c99b01ea3d22bdf5a226f88b22e8d1d7"},"headline":"Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por la suma de USD320 millones","datePublished":"2018-01-05T22:49:26+00:00","dateModified":"2021-12-03T22:55:30+00:00","mainEntityOfPage":{"@id":"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/"},"wordCount":119,"publisher":{"@id":"https:\/\/alcogal.com\/es\/#organization"},"image":{"@id":"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/#primaryimage"},"thumbnailUrl":"https:\/\/alcogal.com\/wp-content\/uploads\/2017\/09\/A.Gerbaud-R.Marquinez.jpg","articleSection":["Transacciones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/","url":"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/","name":"Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por la suma de USD320 millones | Alem\u00e1n, Cordero, Galindo &amp; Lee","isPartOf":{"@id":"https:\/\/alcogal.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/#primaryimage"},"image":{"@id":"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/#primaryimage"},"thumbnailUrl":"https:\/\/alcogal.com\/wp-content\/uploads\/2017\/09\/A.Gerbaud-R.Marquinez.jpg","datePublished":"2018-01-05T22:49:26+00:00","dateModified":"2021-12-03T22:55:30+00:00","breadcrumb":{"@id":"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/#primaryimage","url":"https:\/\/alcogal.com\/wp-content\/uploads\/2017\/09\/A.Gerbaud-R.Marquinez.jpg","contentUrl":"https:\/\/alcogal.com\/wp-content\/uploads\/2017\/09\/A.Gerbaud-R.Marquinez.jpg","width":420,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/alcogal.com\/es\/alcogal-asesoro-alternegy-s-en-su-primera-emision-de-bonos-por-la-suma-de-us320-milllones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alcogal.com\/es\/"},{"@type":"ListItem","position":2,"name":"Alcogal asesor\u00f3 a Alternegy, S.A. en su primera emisi\u00f3n de bonos por la suma de USD320 millones"}]},{"@type":"WebSite","@id":"https:\/\/alcogal.com\/es\/#website","url":"https:\/\/alcogal.com\/es\/","name":"Alem\u00e1n Cordero Galindo & Lee","description":"Firma de Abogados en Panam\u00e1","publisher":{"@id":"https:\/\/alcogal.com\/es\/#organization"},"alternateName":"Alcogal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alcogal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/alcogal.com\/es\/#organization","name":"Aleman, Cordero, Galindo & Lee","alternateName":"Alcogal","url":"https:\/\/alcogal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/alcogal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/04\/logo-alcogal.png","contentUrl":"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/04\/logo-alcogal.png","width":696,"height":696,"caption":"Aleman, Cordero, Galindo & Lee"},"image":{"@id":"https:\/\/alcogal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AlcogalAbogados\/","https:\/\/x.com\/alcogalabogados","https:\/\/www.linkedin.com\/company\/alcogal\/","https:\/\/www.instagram.com\/alcogalabogados\/"],"description":"Since our foundation in 1985, we have established ourselves as one of Panama\u2019s most prestigious law firms. We are a full-service firm with a team of lawyers who provide timely and efficient advice in all practice areas","email":"contact@alcogal.com","telephone":"+507 269-2620","foundingDate":"1985-01-01"},{"@type":"Person","@id":"https:\/\/alcogal.com\/es\/#\/schema\/person\/c99b01ea3d22bdf5a226f88b22e8d1d7","name":"Alcogal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/438173877dc45e2c5735b6ee45d71a1701c94eb9c1fd1d2501655e3db906ad2a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/438173877dc45e2c5735b6ee45d71a1701c94eb9c1fd1d2501655e3db906ad2a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/438173877dc45e2c5735b6ee45d71a1701c94eb9c1fd1d2501655e3db906ad2a?s=96&d=mm&r=g","caption":"Alcogal"},"url":"https:\/\/alcogal.com\/es\/author\/adminmarissa\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/alcogal.com\/wp-content\/uploads\/2017\/09\/A.Gerbaud-R.Marquinez.jpg","_links":{"self":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/posts\/4785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/comments?post=4785"}],"version-history":[{"count":0,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/posts\/4785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/media\/12859"}],"wp:attachment":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/media?parent=4785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/categories?post=4785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/tags?post=4785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}