{"id":2254,"date":"2014-08-31T00:09:01","date_gmt":"2014-08-31T00:09:01","guid":{"rendered":"https:\/\/alcogal.com\/alcogal-assists-cable-and-wireless-panama\/"},"modified":"2022-01-18T21:16:13","modified_gmt":"2022-01-19T02:16:13","slug":"alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel","status":"publish","type":"post","link":"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/","title":{"rendered":"Alcogal asiste a Cable &#038; Wireless Panam\u00e1 en la compra de Grupo Sonitel"},"content":{"rendered":"<p style=\"text-align: justify;\">Alem\u00e1n, Cordero, Galindo &amp; Lee, a trav\u00e9s del esfuerzo conjunto de sus equipos especializados en telecomunicaciones y corporativo \/ fusiones y adquisiciones, asesor\u00f3 a <a href=\"https:\/\/alcogal.com\/es\/\">Cable &amp; Wireless Panama<\/a>, S.A., una subsidiaria de <a href=\"https:\/\/alcogal.com\/es\/\">Cable &amp; Wireless Communications, Plc (CWC)<\/a>, en la adquisici\u00f3n de 12 sociedades de Grupo Sonitel por USD41,280,000.<\/p>\n<p style=\"text-align: justify;\">La transacci\u00f3n, que fue anunciada en agosto de este a\u00f1o, incluy\u00f3 la adquisici\u00f3n de las subsidiarias SSA Sistemas, un proveedor de soluciones integrales de sistemas y de servicios de telecomunicaciones a entidades privadas y p\u00fablicas en Panam\u00e1, El Salvador, Nicaragua y Per\u00fa, y de <a href=\"https:\/\/alcogal.com\/es\/\">Sonset<\/a>, un proveedor de soluciones y servicios de tecnolog\u00eda para peque\u00f1as y medianas empresas en Panam\u00e1, entre otras. Otras subsidiarias de Grupo Sonitel, incluyendo Logistica, un revendedor de hardware, no formaron parte de la transacci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">El equipo de Alcogal a cargo de esta transacci\u00f3n lo lideraron los socios Ra\u00fal Borrell y Alejandro Ferrer. La asociada Rita de la Guardia los apoy\u00f3 en este proyecto. Cable &amp; Wireless Panama, S.A. ha sido cliente de nuestra firma por m\u00e1s de 15 a\u00f1os. Para esta transacci\u00f3n los asesoramos en todas las fases, incluyendo la debida diligencia de todas las compa\u00f1\u00edas y la redacci\u00f3n y negociaci\u00f3n del Acuerdo de Compra de Acciones (SPA, por sus siglas en ingl\u00e9s). Felicitamos a nuestro cliente por este gran logro, que le permitir\u00e1 expandir su presencia en Latinoam\u00e9rica y ampliar la gama de servicios que les ofrece a sus clientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alem\u00e1n, Cordero, Galindo &amp; Lee, a trav\u00e9s del esfuerzo conjunto de sus equipos especializados en telecomunicaciones y corporativo \/ fusiones y adquisiciones, asesor\u00f3 a Cable &amp; Wireless Panama, S.A., una subsidiaria de Cable &amp; Wireless Communications, Plc (CWC), en la adquisici\u00f3n de 12 sociedades de Grupo Sonitel por USD41,280,000. La transacci\u00f3n, que fue anunciada en &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/\"> <span class=\"screen-reader-text\">Alcogal asiste a Cable &#038; Wireless Panam\u00e1 en la compra de Grupo Sonitel<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":12775,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2280,47],"tags":[],"class_list":["post-2254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia-y-recursos-naturales","category-transacciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Alcogal asiste a Cable &amp; Wireless Panam\u00e1 en la compra de Grupo Sonitel | Alem\u00e1n, Cordero, Galindo &amp; Lee<\/title>\n<meta name=\"description\" content=\"Alcogal asiste a Cable &amp; Wireless Panam\u00e1 en la compra de Grupo Sonitel en la adquisici\u00f3n de 12 sociedades por USD41,280,000.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alcogal asiste a Cable &amp; Wireless Panam\u00e1 en la compra de Grupo Sonitel\" \/>\n<meta property=\"og:description\" content=\"Alcogal asiste a Cable &amp; Wireless Panam\u00e1 en la compra de Grupo Sonitel en la adquisici\u00f3n de 12 sociedades por USD41,280,000.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/\" \/>\n<meta property=\"og:site_name\" content=\"Alem\u00e1n, Cordero, Galindo &amp; Lee\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AlcogalAbogados\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-08-31T00:09:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-19T02:16:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/alcogal.com\/wp-content\/uploads\/2017\/07\/Alcogal-assists-Cable-and-Wireless.jpg?fit=844%2C452&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"844\" \/>\n\t<meta property=\"og:image:height\" content=\"452\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alcogal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@alcogalabogados\" \/>\n<meta name=\"twitter:site\" content=\"@alcogalabogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alcogal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\\\/\"},\"author\":{\"name\":\"Alcogal\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#\\\/schema\\\/person\\\/c99b01ea3d22bdf5a226f88b22e8d1d7\"},\"headline\":\"Alcogal asiste a Cable &#038; Wireless Panam\u00e1 en la compra de Grupo Sonitel\",\"datePublished\":\"2014-08-31T00:09:01+00:00\",\"dateModified\":\"2022-01-19T02:16:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\\\/\"},\"wordCount\":266,\"publisher\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Alcogal-assists-Cable-and-Wireless.jpg\",\"articleSection\":[\"Energ\u00eda y recursos naturales\",\"Transacciones\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\\\/\",\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\\\/\",\"name\":\"Alcogal asiste a Cable & Wireless Panam\u00e1 en la compra de Grupo Sonitel | Alem\u00e1n, Cordero, Galindo &amp; Lee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Alcogal-assists-Cable-and-Wireless.jpg\",\"datePublished\":\"2014-08-31T00:09:01+00:00\",\"dateModified\":\"2022-01-19T02:16:13+00:00\",\"description\":\"Alcogal asiste a Cable & Wireless Panam\u00e1 en la compra de Grupo Sonitel en la adquisici\u00f3n de 12 sociedades por USD41,280,000.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Alcogal-assists-Cable-and-Wireless.jpg\",\"contentUrl\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Alcogal-assists-Cable-and-Wireless.jpg\",\"width\":844,\"height\":452},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alcogal.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alcogal asiste a Cable &#038; Wireless Panam\u00e1 en la compra de Grupo Sonitel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/\",\"name\":\"Alem\u00e1n Cordero Galindo & Lee\",\"description\":\"Firma de Abogados en Panam\u00e1\",\"publisher\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#organization\"},\"alternateName\":\"Alcogal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alcogal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#organization\",\"name\":\"Aleman, Cordero, Galindo & Lee\",\"alternateName\":\"Alcogal\",\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-alcogal.png\",\"contentUrl\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-alcogal.png\",\"width\":696,\"height\":696,\"caption\":\"Aleman, Cordero, Galindo & Lee\"},\"image\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AlcogalAbogados\\\/\",\"https:\\\/\\\/x.com\\\/alcogalabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/alcogal\\\/\",\"https:\\\/\\\/www.instagram.com\\\/alcogalabogados\\\/\"],\"description\":\"Since our foundation in 1985, we have established ourselves as one of Panama\u2019s most prestigious law firms. We are a full-service firm with a team of lawyers who provide timely and efficient advice in all practice areas\",\"email\":\"contact@alcogal.com\",\"telephone\":\"+507 269-2620\",\"foundingDate\":\"1985-01-01\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#\\\/schema\\\/person\\\/c99b01ea3d22bdf5a226f88b22e8d1d7\",\"name\":\"Alcogal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/438173877dc45e2c5735b6ee45d71a1701c94eb9c1fd1d2501655e3db906ad2a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/438173877dc45e2c5735b6ee45d71a1701c94eb9c1fd1d2501655e3db906ad2a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/438173877dc45e2c5735b6ee45d71a1701c94eb9c1fd1d2501655e3db906ad2a?s=96&d=mm&r=g\",\"caption\":\"Alcogal\"},\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/author\\\/adminmarissa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alcogal asiste a Cable & Wireless Panam\u00e1 en la compra de Grupo Sonitel | Alem\u00e1n, Cordero, Galindo &amp; Lee","description":"Alcogal asiste a Cable & Wireless Panam\u00e1 en la compra de Grupo Sonitel en la adquisici\u00f3n de 12 sociedades por USD41,280,000.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/","og_locale":"es_ES","og_type":"article","og_title":"Alcogal asiste a Cable & Wireless Panam\u00e1 en la compra de Grupo Sonitel","og_description":"Alcogal asiste a Cable & Wireless Panam\u00e1 en la compra de Grupo Sonitel en la adquisici\u00f3n de 12 sociedades por USD41,280,000.","og_url":"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/","og_site_name":"Alem\u00e1n, Cordero, Galindo &amp; Lee","article_publisher":"https:\/\/www.facebook.com\/AlcogalAbogados\/","article_published_time":"2014-08-31T00:09:01+00:00","article_modified_time":"2022-01-19T02:16:13+00:00","og_image":[{"width":844,"height":452,"url":"https:\/\/i0.wp.com\/alcogal.com\/wp-content\/uploads\/2017\/07\/Alcogal-assists-Cable-and-Wireless.jpg?fit=844%2C452&ssl=1","type":"image\/jpeg"}],"author":"Alcogal","twitter_card":"summary_large_image","twitter_creator":"@alcogalabogados","twitter_site":"@alcogalabogados","twitter_misc":{"Escrito por":"Alcogal","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/#article","isPartOf":{"@id":"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/"},"author":{"name":"Alcogal","@id":"https:\/\/alcogal.com\/es\/#\/schema\/person\/c99b01ea3d22bdf5a226f88b22e8d1d7"},"headline":"Alcogal asiste a Cable &#038; Wireless Panam\u00e1 en la compra de Grupo Sonitel","datePublished":"2014-08-31T00:09:01+00:00","dateModified":"2022-01-19T02:16:13+00:00","mainEntityOfPage":{"@id":"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/"},"wordCount":266,"publisher":{"@id":"https:\/\/alcogal.com\/es\/#organization"},"image":{"@id":"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/#primaryimage"},"thumbnailUrl":"https:\/\/alcogal.com\/wp-content\/uploads\/2017\/07\/Alcogal-assists-Cable-and-Wireless.jpg","articleSection":["Energ\u00eda y recursos naturales","Transacciones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/","url":"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/","name":"Alcogal asiste a Cable & Wireless Panam\u00e1 en la compra de Grupo Sonitel | Alem\u00e1n, Cordero, Galindo &amp; Lee","isPartOf":{"@id":"https:\/\/alcogal.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/#primaryimage"},"image":{"@id":"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/#primaryimage"},"thumbnailUrl":"https:\/\/alcogal.com\/wp-content\/uploads\/2017\/07\/Alcogal-assists-Cable-and-Wireless.jpg","datePublished":"2014-08-31T00:09:01+00:00","dateModified":"2022-01-19T02:16:13+00:00","description":"Alcogal asiste a Cable & Wireless Panam\u00e1 en la compra de Grupo Sonitel en la adquisici\u00f3n de 12 sociedades por USD41,280,000.","breadcrumb":{"@id":"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/#primaryimage","url":"https:\/\/alcogal.com\/wp-content\/uploads\/2017\/07\/Alcogal-assists-Cable-and-Wireless.jpg","contentUrl":"https:\/\/alcogal.com\/wp-content\/uploads\/2017\/07\/Alcogal-assists-Cable-and-Wireless.jpg","width":844,"height":452},{"@type":"BreadcrumbList","@id":"https:\/\/alcogal.com\/es\/alcogal-asiste-a-cable-wireless-panama-en-la-compra-de-grupo-sonitel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alcogal.com\/es\/"},{"@type":"ListItem","position":2,"name":"Alcogal asiste a Cable &#038; Wireless Panam\u00e1 en la compra de Grupo Sonitel"}]},{"@type":"WebSite","@id":"https:\/\/alcogal.com\/es\/#website","url":"https:\/\/alcogal.com\/es\/","name":"Alem\u00e1n Cordero Galindo & Lee","description":"Firma de Abogados en Panam\u00e1","publisher":{"@id":"https:\/\/alcogal.com\/es\/#organization"},"alternateName":"Alcogal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alcogal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/alcogal.com\/es\/#organization","name":"Aleman, Cordero, Galindo & Lee","alternateName":"Alcogal","url":"https:\/\/alcogal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/alcogal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/04\/logo-alcogal.png","contentUrl":"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/04\/logo-alcogal.png","width":696,"height":696,"caption":"Aleman, Cordero, Galindo & Lee"},"image":{"@id":"https:\/\/alcogal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AlcogalAbogados\/","https:\/\/x.com\/alcogalabogados","https:\/\/www.linkedin.com\/company\/alcogal\/","https:\/\/www.instagram.com\/alcogalabogados\/"],"description":"Since our foundation in 1985, we have established ourselves as one of Panama\u2019s most prestigious law firms. We are a full-service firm with a team of lawyers who provide timely and efficient advice in all practice areas","email":"contact@alcogal.com","telephone":"+507 269-2620","foundingDate":"1985-01-01"},{"@type":"Person","@id":"https:\/\/alcogal.com\/es\/#\/schema\/person\/c99b01ea3d22bdf5a226f88b22e8d1d7","name":"Alcogal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/438173877dc45e2c5735b6ee45d71a1701c94eb9c1fd1d2501655e3db906ad2a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/438173877dc45e2c5735b6ee45d71a1701c94eb9c1fd1d2501655e3db906ad2a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/438173877dc45e2c5735b6ee45d71a1701c94eb9c1fd1d2501655e3db906ad2a?s=96&d=mm&r=g","caption":"Alcogal"},"url":"https:\/\/alcogal.com\/es\/author\/adminmarissa\/"}]}},"jetpack_featured_media_url":"https:\/\/alcogal.com\/wp-content\/uploads\/2017\/07\/Alcogal-assists-Cable-and-Wireless.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/posts\/2254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/comments?post=2254"}],"version-history":[{"count":0,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/posts\/2254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/media\/12775"}],"wp:attachment":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/media?parent=2254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/categories?post=2254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/tags?post=2254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}