{"id":12233,"date":"2021-09-09T03:22:52","date_gmt":"2021-09-09T03:22:52","guid":{"rendered":"https:\/\/alcogal.com\/\/abogados\/patricia-cordero-a\/"},"modified":"2026-02-12T11:57:56","modified_gmt":"2026-02-12T16:57:56","slug":"patricia-cordero-a","status":"publish","type":"page","link":"https:\/\/alcogal.com\/es\/abogados-3\/patricia-cordero-a\/","title":{"rendered":"Patricia Cordero A."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12233\" class=\"elementor elementor-12233 elementor-9742\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-064365a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"064365a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a88f171\" data-id=\"a88f171\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d812eb elementor-widget elementor-widget-heading\" data-id=\"6d812eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">PATRICIA CORDERO A.<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58b1d63 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"58b1d63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a477ff1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a477ff1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-f52d768\" data-id=\"f52d768\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-30b47dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30b47dc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cf376bb\" data-id=\"cf376bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c596620 elementor-widget elementor-widget-image\" data-id=\"c596620\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/alcogal.com\/wp-content\/uploads\/2014\/10\/webcolor-20.webp\" class=\"attachment-large size-large wp-image-12738\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c8f39b9\" data-id=\"c8f39b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e09f190 elementor-view-stacked elementor-shape-square elementor-position-inline-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"e09f190\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tpcordero@alcogal.com\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfd0d14 elementor-view-stacked elementor-shape-square elementor-position-inline-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"cfd0d14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t+(507) 269-2620\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7071fa6 elementor-view-stacked elementor-shape-square elementor-position-inline-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7071fa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSocia\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ad8cab elementor-view-stacked elementor-shape-square elementor-position-inline-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5ad8cab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCiudad de Panam\u00e1\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-244896d\" data-id=\"244896d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b25436 elementor-widget elementor-widget-heading\" data-id=\"4b25436\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00c1reas de pr\u00e1ctica\u200b<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc7755f elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"cc7755f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alcogal.com\/es\/abogados-de-banca-en-panama\/%20\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Banca<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alcogal.com\/es\/abogados-de-fusiones-y-adquisiciones-en-panama\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Corporativo, fusiones y adquisiciones<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alcogal.com\/es\/abogados-de-finanzas-en-panama\/%20\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Finanzas<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alcogal.com\/es\/abogados-de-mercados-capitales-en-panama\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mercados de capitales<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9faa412 elementor-widget elementor-widget-heading\" data-id=\"9faa412\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Admisi\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf99983 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"cf99983\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2017, Panam\u00e1<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f46a64 elementor-widget elementor-widget-heading\" data-id=\"1f46a64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Idiomas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce037d0 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ce037d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Espa\u00f1ol<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ingl\u00e9s<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aab2324 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aab2324\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d320330\" data-id=\"d320330\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-881e935 elementor-widget elementor-widget-text-editor\" data-id=\"881e935\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Educaci\u00f3n<\/h3>\n<ul>\n<li>Juris Doctor (J.D.), Universidad de Emory, Atlanta, Georgia (2010)<\/li>\n<li>Licenciatura en Mercadeo, Universidad de Nueva York, Ciudad de Nueva York, Nueva York (2007)<\/li>\n<\/ul>\n<h3>Experiencia<\/h3>\n<ul>\n<li>Socia en en Alem\u00e1n, Cordero, Galindo &amp; Lee (2022-presente)<\/li>\n<li>Asociada S\u00e9nior en Alem\u00e1n, Cordero, Galindo &amp; Lee (2019-2022)<\/li>\n<li>Asociada en Alem\u00e1n, Cordero, Galindo &amp; Lee (2010-2019)<\/li>\n<\/ul>\n<h3>Membres\u00edas<\/h3><ul>\n<li>Directora, Alem\u00e1n, Cordero, Galindo &amp; Lee Trust<\/li>\n<li>Directora, Fundaci\u00f3n Educativa Juan Pablo II<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-47e541e\" data-id=\"47e541e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8949975 elementor-widget elementor-widget-heading\" data-id=\"8949975\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><font color=\"#00577d\"><span style=\"font-size: 25px\">Rankings<\/span><\/font><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5d57cbc elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d57cbc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1c30c1f\" data-id=\"1c30c1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d78662f elementor-widget elementor-widget-image\" data-id=\"d78662f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"420\" src=\"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/08\/patricia-cordero-latam-2026.webp\" class=\"attachment-large size-large wp-image-22111\" alt=\"\" srcset=\"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/08\/patricia-cordero-latam-2026.webp 500w, https:\/\/alcogal.com\/wp-content\/uploads\/2025\/08\/patricia-cordero-latam-2026-300x252.webp 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4b45ec2\" data-id=\"4b45ec2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff79e3a elementor-widget elementor-widget-image\" data-id=\"ff79e3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/10\/next-gen-26.svg\" class=\"attachment-full size-full wp-image-22374\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a1178fb\" data-id=\"a1178fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f79f5d1 elementor-widget elementor-widget-image\" data-id=\"f79f5d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"498\" src=\"https:\/\/alcogal.com\/wp-content\/uploads\/2026\/01\/lexology-1024x498.webp\" class=\"attachment-large size-large wp-image-22882\" alt=\"\" srcset=\"https:\/\/alcogal.com\/wp-content\/uploads\/2026\/01\/lexology-1024x498.webp 1024w, https:\/\/alcogal.com\/wp-content\/uploads\/2026\/01\/lexology-300x146.webp 300w, https:\/\/alcogal.com\/wp-content\/uploads\/2026\/01\/lexology-768x374.webp 768w, https:\/\/alcogal.com\/wp-content\/uploads\/2026\/01\/lexology.webp 1299w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-43d4db3 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43d4db3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8d782b8\" data-id=\"8d782b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c92d979 elementor-widget elementor-widget-image\" data-id=\"c92d979\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"860\" src=\"https:\/\/alcogal.com\/wp-content\/uploads\/2026\/02\/Cordero-Patricia-bg-removed-1024x860.webp\" class=\"attachment-large size-large wp-image-23088\" alt=\"\" srcset=\"https:\/\/alcogal.com\/wp-content\/uploads\/2026\/02\/Cordero-Patricia-bg-removed-1024x860.webp 1024w, https:\/\/alcogal.com\/wp-content\/uploads\/2026\/02\/Cordero-Patricia-bg-removed-300x252.webp 300w, https:\/\/alcogal.com\/wp-content\/uploads\/2026\/02\/Cordero-Patricia-bg-removed-768x645.webp 768w, https:\/\/alcogal.com\/wp-content\/uploads\/2026\/02\/Cordero-Patricia-bg-removed.webp 1072w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d55ab0a\" data-id=\"d55ab0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a17c375 elementor-widget elementor-widget-image\" data-id=\"a17c375\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/11\/iflr1000-rising-star-partner-2025-1024x1024.webp\" class=\"attachment-large size-large wp-image-22716\" alt=\"IFLR 1000 - Rising Star Partner\" srcset=\"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/11\/iflr1000-rising-star-partner-2025-1024x1024.webp 1024w, https:\/\/alcogal.com\/wp-content\/uploads\/2025\/11\/iflr1000-rising-star-partner-2025-300x300.webp 300w, https:\/\/alcogal.com\/wp-content\/uploads\/2025\/11\/iflr1000-rising-star-partner-2025-150x150.webp 150w, https:\/\/alcogal.com\/wp-content\/uploads\/2025\/11\/iflr1000-rising-star-partner-2025-768x768.webp 768w, https:\/\/alcogal.com\/wp-content\/uploads\/2025\/11\/iflr1000-rising-star-partner-2025.webp 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d41c9b0\" data-id=\"d41c9b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>PATRICIA CORDERO A. pcordero@alcogal.com +(507) 269-2620 Socia Ciudad de Panam\u00e1 \u00c1reas de pr\u00e1ctica\u200b Banca Corporativo, fusiones y adquisiciones Finanzas Mercados de capitales Admisi\u00f3n 2017, Panam\u00e1 Idiomas Espa\u00f1ol Ingl\u00e9s Educaci\u00f3n Juris Doctor (J.D.), Universidad de Emory, Atlanta, Georgia (2010) Licenciatura en Mercadeo, Universidad de Nueva York, Ciudad de Nueva York, Nueva York (2007) Experiencia Socia en &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/alcogal.com\/es\/abogados-3\/patricia-cordero-a\/\"> <span class=\"screen-reader-text\">Patricia Cordero A.<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":11783,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"","footnotes":""},"class_list":["post-12233","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Patricia Cordero A. | Alem\u00e1n, Cordero, Galindo &amp; Lee<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alcogal.com\/es\/abogados-3\/patricia-cordero-a\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Patricia Cordero A.\" \/>\n<meta property=\"og:description\" content=\"PATRICIA CORDERO A. pcordero@alcogal.com +(507) 269-2620 Socia Ciudad de Panam\u00e1 \u00c1reas de pr\u00e1ctica\u200b Banca Corporativo, fusiones y adquisiciones Finanzas Mercados de capitales Admisi\u00f3n 2017, Panam\u00e1 Idiomas Espa\u00f1ol Ingl\u00e9s Educaci\u00f3n Juris Doctor (J.D.), Universidad de Emory, Atlanta, Georgia (2010) Licenciatura en Mercadeo, Universidad de Nueva York, Ciudad de Nueva York, Nueva York (2007) Experiencia Socia en &hellip; Patricia Cordero A. Leer m\u00e1s &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alcogal.com\/es\/abogados-3\/patricia-cordero-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Alem\u00e1n, Cordero, Galindo &amp; Lee\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AlcogalAbogados\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-12T16:57:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alcogal.com\/wp-content\/uploads\/2014\/10\/webcolor-20.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@alcogalabogados\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/abogados-3\\\/patricia-cordero-a\\\/\",\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/abogados-3\\\/patricia-cordero-a\\\/\",\"name\":\"Patricia Cordero A. | Alem\u00e1n, Cordero, Galindo &amp; Lee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/abogados-3\\\/patricia-cordero-a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/abogados-3\\\/patricia-cordero-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/webcolor-20.webp\",\"datePublished\":\"2021-09-09T03:22:52+00:00\",\"dateModified\":\"2026-02-12T16:57:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/abogados-3\\\/patricia-cordero-a\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alcogal.com\\\/es\\\/abogados-3\\\/patricia-cordero-a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/abogados-3\\\/patricia-cordero-a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/webcolor-20.webp\",\"contentUrl\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/webcolor-20.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/abogados-3\\\/patricia-cordero-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alcogal.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abogados\",\"item\":\"https:\\\/\\\/alcogal.com\\\/es\\\/lawyers\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Patricia Cordero A.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/\",\"name\":\"Alem\u00e1n Cordero Galindo & Lee\",\"description\":\"Firma de Abogados en Panam\u00e1\",\"publisher\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#organization\"},\"alternateName\":\"Alcogal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alcogal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#organization\",\"name\":\"Aleman, Cordero, Galindo & Lee\",\"alternateName\":\"Alcogal\",\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-alcogal.png\",\"contentUrl\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-alcogal.png\",\"width\":696,\"height\":696,\"caption\":\"Aleman, Cordero, Galindo & Lee\"},\"image\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AlcogalAbogados\\\/\",\"https:\\\/\\\/x.com\\\/alcogalabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/alcogal\\\/\",\"https:\\\/\\\/www.instagram.com\\\/alcogalabogados\\\/\"],\"description\":\"Since our foundation in 1985, we have established ourselves as one of Panama\u2019s most prestigious law firms. We are a full-service firm with a team of lawyers who provide timely and efficient advice in all practice areas\",\"email\":\"contact@alcogal.com\",\"telephone\":\"+507 269-2620\",\"foundingDate\":\"1985-01-01\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Patricia Cordero A. | Alem\u00e1n, Cordero, Galindo &amp; Lee","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alcogal.com\/es\/abogados-3\/patricia-cordero-a\/","og_locale":"es_ES","og_type":"article","og_title":"Patricia Cordero A.","og_description":"PATRICIA CORDERO A. pcordero@alcogal.com +(507) 269-2620 Socia Ciudad de Panam\u00e1 \u00c1reas de pr\u00e1ctica\u200b Banca Corporativo, fusiones y adquisiciones Finanzas Mercados de capitales Admisi\u00f3n 2017, Panam\u00e1 Idiomas Espa\u00f1ol Ingl\u00e9s Educaci\u00f3n Juris Doctor (J.D.), Universidad de Emory, Atlanta, Georgia (2010) Licenciatura en Mercadeo, Universidad de Nueva York, Ciudad de Nueva York, Nueva York (2007) Experiencia Socia en &hellip; Patricia Cordero A. Leer m\u00e1s &raquo;","og_url":"https:\/\/alcogal.com\/es\/abogados-3\/patricia-cordero-a\/","og_site_name":"Alem\u00e1n, Cordero, Galindo &amp; Lee","article_publisher":"https:\/\/www.facebook.com\/AlcogalAbogados\/","article_modified_time":"2026-02-12T16:57:56+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/alcogal.com\/wp-content\/uploads\/2014\/10\/webcolor-20.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@alcogalabogados","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alcogal.com\/es\/abogados-3\/patricia-cordero-a\/","url":"https:\/\/alcogal.com\/es\/abogados-3\/patricia-cordero-a\/","name":"Patricia Cordero A. | Alem\u00e1n, Cordero, Galindo &amp; Lee","isPartOf":{"@id":"https:\/\/alcogal.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alcogal.com\/es\/abogados-3\/patricia-cordero-a\/#primaryimage"},"image":{"@id":"https:\/\/alcogal.com\/es\/abogados-3\/patricia-cordero-a\/#primaryimage"},"thumbnailUrl":"https:\/\/alcogal.com\/wp-content\/uploads\/2014\/10\/webcolor-20.webp","datePublished":"2021-09-09T03:22:52+00:00","dateModified":"2026-02-12T16:57:56+00:00","breadcrumb":{"@id":"https:\/\/alcogal.com\/es\/abogados-3\/patricia-cordero-a\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alcogal.com\/es\/abogados-3\/patricia-cordero-a\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/alcogal.com\/es\/abogados-3\/patricia-cordero-a\/#primaryimage","url":"https:\/\/alcogal.com\/wp-content\/uploads\/2014\/10\/webcolor-20.webp","contentUrl":"https:\/\/alcogal.com\/wp-content\/uploads\/2014\/10\/webcolor-20.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/alcogal.com\/es\/abogados-3\/patricia-cordero-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alcogal.com\/es\/"},{"@type":"ListItem","position":2,"name":"Abogados","item":"https:\/\/alcogal.com\/es\/lawyers\/"},{"@type":"ListItem","position":3,"name":"Patricia Cordero A."}]},{"@type":"WebSite","@id":"https:\/\/alcogal.com\/es\/#website","url":"https:\/\/alcogal.com\/es\/","name":"Alem\u00e1n Cordero Galindo & Lee","description":"Firma de Abogados en Panam\u00e1","publisher":{"@id":"https:\/\/alcogal.com\/es\/#organization"},"alternateName":"Alcogal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alcogal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/alcogal.com\/es\/#organization","name":"Aleman, Cordero, Galindo & Lee","alternateName":"Alcogal","url":"https:\/\/alcogal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/alcogal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/04\/logo-alcogal.png","contentUrl":"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/04\/logo-alcogal.png","width":696,"height":696,"caption":"Aleman, Cordero, Galindo & Lee"},"image":{"@id":"https:\/\/alcogal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AlcogalAbogados\/","https:\/\/x.com\/alcogalabogados","https:\/\/www.linkedin.com\/company\/alcogal\/","https:\/\/www.instagram.com\/alcogalabogados\/"],"description":"Since our foundation in 1985, we have established ourselves as one of Panama\u2019s most prestigious law firms. We are a full-service firm with a team of lawyers who provide timely and efficient advice in all practice areas","email":"contact@alcogal.com","telephone":"+507 269-2620","foundingDate":"1985-01-01"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/pages\/12233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/comments?post=12233"}],"version-history":[{"count":43,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/pages\/12233\/revisions"}],"predecessor-version":[{"id":23094,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/pages\/12233\/revisions\/23094"}],"up":[{"embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/pages\/11783"}],"wp:attachment":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/media?parent=12233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}