{"id":12009,"date":"2021-09-09T04:42:07","date_gmt":"2021-09-09T04:42:07","guid":{"rendered":"https:\/\/alcogal.com\/\/other-practice-areas\/"},"modified":"2022-03-02T22:33:08","modified_gmt":"2022-03-03T03:33:08","slug":"otras-areas-de-practica","status":"publish","type":"page","link":"https:\/\/alcogal.com\/es\/otras-areas-de-practica\/","title":{"rendered":"Otras \u00c1reas de Pr\u00e1ctica"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12009\" class=\"elementor elementor-12009 elementor-9839\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4de05bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4de05bf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0117377\" data-id=\"0117377\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b280c85 elementor-widget elementor-widget-heading\" data-id=\"b280c85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xxl\">OTRAS \u00c1REAS DE PR\u00c1CTICA<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00b8a39 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00b8a39\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-781af40\" data-id=\"781af40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2af4ee8 elementor-widget elementor-widget-heading\" data-id=\"2af4ee8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Antimonopolio<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0f22de elementor-widget elementor-widget-text-editor\" data-id=\"e0f22de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAlcogal asesora a sus clientes en una amplia gama de asuntos antimonopol\u00edsticos, incluyendo fusiones y adquisiciones, regulaciones comerciales, litigios antimonopol\u00edsticos y otros temas recurrentes del derecho de competencia.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a2a6cbc\" data-id=\"a2a6cbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92e8154 elementor-widget elementor-widget-heading\" data-id=\"92e8154\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comercio internacional<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-002aeb7 elementor-widget elementor-widget-text-editor\" data-id=\"002aeb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNuestro equipo de comercio internacional ofrece una combinaci\u00f3n \u00fanica de experiencia en toda la gama de asuntos regulatorios en torno al comercio y las inversiones internacionales, incluyendo el cumplimiento del Acuerdo de Promoci\u00f3n Comercial entre Panam\u00e1 y Estados Unidos, del Tratado Bilateral de Inversiones entre Panam\u00e1 y Estados Unidos, y de las normas de la Organizaci\u00f3n Mundial del Comercio, entre otros.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-947821c\" data-id=\"947821c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ca15f4 elementor-widget elementor-widget-heading\" data-id=\"9ca15f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Fideicomisos y planificaci\u00f3n patrimonial<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1beddc1 elementor-widget elementor-widget-text-editor\" data-id=\"1beddc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alcogal tiene una pr\u00e1ctica creciente de fideicomisos y planificaci\u00f3n de patrimonios a nivel mundial, la cual incluye la representaci\u00f3n de individuos, familias, empresas privadas y organizaciones de caridad, tanto en Panam\u00e1 como en el extranjero. Apoy\u00e1ndonos en los conocimientos colectivos de nuestros abogados de otros grupos de pr\u00e1ctica, representamos continuamente a nuestros clientes en asuntos corporativos, de asociaciones, de bienes ra\u00edces, en la gesti\u00f3n de sus patrimonios y en el cumplimiento de la ley local de impuestos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a7f22a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a7f22a0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c38f1d5\" data-id=\"c38f1d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b428dc elementor-widget elementor-widget-heading\" data-id=\"4b428dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Inmigraci\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cab438c elementor-widget elementor-widget-text-editor\" data-id=\"cab438c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNuestro grupo de inmigraci\u00f3n tiene una gran experiencia trabajando con corporaciones multinacionales y clientes extranjeros en la reubicaci\u00f3n, inversi\u00f3n o realizaci\u00f3n de operaciones comerciales en Panam\u00e1. Alcogal representa a las empresas extranjeras y nacionales, y sus respectivos empleados, en todos los aspectos de asuntos de inmigraci\u00f3n, incluidas las solicitudes de residencia permanente y los permisos de trabajo.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c967ce2\" data-id=\"c967ce2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bfdcbd elementor-widget elementor-widget-heading\" data-id=\"0bfdcbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Laboral<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55759a8 elementor-widget elementor-widget-text-editor\" data-id=\"55759a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAlcogal tiene amplia experiencia en derecho laboral tradicional. Proveemos asesoramiento laboral especializado con respecto a fusiones y adquisiciones, asuntos de beneficios para empleados, respuestas a disputas y negociaci\u00f3n y administraci\u00f3n de contratos laborales con sindicatos.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-382448b\" data-id=\"382448b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecbc305 elementor-widget elementor-widget-heading\" data-id=\"ecbc305\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Mar\u00edtimo e instalaciones portuarias<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b0d58d elementor-widget elementor-widget-text-editor\" data-id=\"5b0d58d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNuestro equipo de derecho mar\u00edtimo cuenta con una experiencia significativa en materia de naves y transporte mar\u00edtimo. Hemos asesorado a algunas de las compa\u00f1\u00edas l\u00edderes a nivel mundial en la industria naviera y mar\u00edtima. Entre varios otros temas relacionados a esta industria, Alcogal asesora a sus clientes con respecto a la construcci\u00f3n, el registro, la operaci\u00f3n y el financiamiento de buques, barcazas, plataformas de perforaci\u00f3n, buques cisterna de GNL y varios otros tipos de barcos utilizados en todo el mundo.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2cdefd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2cdefd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-90e9f85\" data-id=\"90e9f85\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-979b9ba elementor-widget elementor-widget-heading\" data-id=\"979b9ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Propiedad intelectual<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f90ddd elementor-widget elementor-widget-text-editor\" data-id=\"2f90ddd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEl equipo de propiedad intelectual de Alcogal re\u00fane a abogados de varias \u00e1reas de pr\u00e1ctica para ayudar a nuestros clientes con todo el espectro de asuntos de propiedad intelectual y tecnolog\u00eda que \u00e9stos enfrentan. Nuestros abogados asesoran a los clientes en materia de aplicaci\u00f3n de patentes, marcas y otros derechos de propiedad intelectual, y los aconsejan con respecto a posibles estrategias para asegurar sus intereses en propiedades intelectuales.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2111df2\" data-id=\"2111df2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3723a88 elementor-widget elementor-widget-heading\" data-id=\"3723a88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Seguros<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e82b28d elementor-widget elementor-widget-text-editor\" data-id=\"e82b28d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNuestro equipo de abogados cuenta con vasta experiencia en materia de seguros y reaseguros, incluyendo la absoluci\u00f3n de consultas a aseguradoras, reaseguradoras y bancos sobre temas de seguros y reaseguros, la atenci\u00f3n de procesos administrativos ante la Superintendencia de Seguros y Reaseguros, adem\u00e1s de controversias y procesos judiciales en materia de seguros. A su vez, nuestra firma ha brindado servicios de asesor\u00eda legal a la Superintendencia de Seguros y Reaseguros.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9493fd6\" data-id=\"9493fd6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cebb60e elementor-widget elementor-widget-heading\" data-id=\"cebb60e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Telecomunicaciones<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7ff02a elementor-widget elementor-widget-text-editor\" data-id=\"c7ff02a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAlcogal emplea un enfoque multidisciplinario para abordar las necesidades m\u00e1s apremiantes de nuestros clientes. Nuestro equipo de telecomunicaciones trabaja en estrecha colaboraci\u00f3n con nuestros clientes en sus transacciones de fusiones y adquisiciones, banca y mercados de capitales. Adem\u00e1s, en conjunto con otros equipos dentro de la firma, nuestros talentosos abogados asesoran recurrentemente a nuestros clientes de telecomunicaciones sobre temas tributarios, pr\u00e1cticas antimonopol\u00edsticas, cumplimiento normativo, propiedad intelectual, litigios, entre otros asuntos.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7aa2ee0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7aa2ee0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a4342bd\" data-id=\"a4342bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d88963f elementor-widget elementor-widget-heading\" data-id=\"d88963f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Televisi\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93ae9bd elementor-widget elementor-widget-text-editor\" data-id=\"93ae9bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tComo parte de nuestros servicios legales en materia de servicios p\u00fablicos, nuestra firma tambi\u00e9n brinda a sus clientes asistencia legal respecto a la prestaci\u00f3n del servicio p\u00fablico de Televisi\u00f3n, tanto en temas regulatorios como contractuales.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3f79415\" data-id=\"3f79415\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3323343\" data-id=\"3323343\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bfc322c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bfc322c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c80d33\" data-id=\"6c80d33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fb5398 elementor-widget elementor-widget-spacer\" data-id=\"6fb5398\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>OTRAS \u00c1REAS DE PR\u00c1CTICA Antimonopolio Alcogal asesora a sus clientes en una amplia gama de asuntos antimonopol\u00edsticos, incluyendo fusiones y adquisiciones, regulaciones comerciales, litigios antimonopol\u00edsticos y otros temas recurrentes del derecho de competencia. Comercio internacional Nuestro equipo de comercio internacional ofrece una combinaci\u00f3n \u00fanica de experiencia en toda la gama de asuntos regulatorios en torno &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/alcogal.com\/es\/otras-areas-de-practica\/\"> <span class=\"screen-reader-text\">Otras \u00c1reas de Pr\u00e1ctica<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"","footnotes":""},"class_list":["post-12009","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Otras \u00c1reas de Pr\u00e1ctica | Alem\u00e1n, Cordero, Galindo &amp; Lee<\/title>\n<meta name=\"description\" content=\"Immigration, Intellectual property, International trade, Labor Maritime and port facilities, Telecommunications, Insurance and more\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alcogal.com\/es\/otras-areas-de-practica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Otras \u00c1reas de Pr\u00e1ctica\" \/>\n<meta property=\"og:description\" content=\"Immigration, Intellectual property, International trade, Labor Maritime and port facilities, Telecommunications, Insurance and more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alcogal.com\/es\/otras-areas-de-practica\/\" \/>\n<meta property=\"og:site_name\" content=\"Alem\u00e1n, Cordero, Galindo &amp; Lee\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AlcogalAbogados\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-03T03:33:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alcogal.com\/wp-content\/uploads\/2026\/02\/alcogal-new-og.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@alcogalabogados\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/otras-areas-de-practica\\\/\",\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/otras-areas-de-practica\\\/\",\"name\":\"Otras \u00c1reas de Pr\u00e1ctica | Alem\u00e1n, Cordero, Galindo &amp; Lee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#website\"},\"datePublished\":\"2021-09-09T04:42:07+00:00\",\"dateModified\":\"2022-03-03T03:33:08+00:00\",\"description\":\"Immigration, Intellectual property, International trade, Labor Maritime and port facilities, Telecommunications, Insurance and more\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/otras-areas-de-practica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alcogal.com\\\/es\\\/otras-areas-de-practica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/otras-areas-de-practica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alcogal.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Otras \u00c1reas de Pr\u00e1ctica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/\",\"name\":\"Alem\u00e1n Cordero Galindo & Lee\",\"description\":\"Firma de Abogados en Panam\u00e1\",\"publisher\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#organization\"},\"alternateName\":\"Alcogal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alcogal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#organization\",\"name\":\"Aleman, Cordero, Galindo & Lee\",\"alternateName\":\"Alcogal\",\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-alcogal.png\",\"contentUrl\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-alcogal.png\",\"width\":696,\"height\":696,\"caption\":\"Aleman, Cordero, Galindo & Lee\"},\"image\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AlcogalAbogados\\\/\",\"https:\\\/\\\/x.com\\\/alcogalabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/alcogal\\\/\",\"https:\\\/\\\/www.instagram.com\\\/alcogalabogados\\\/\"],\"description\":\"Since our foundation in 1985, we have established ourselves as one of Panama\u2019s most prestigious law firms. We are a full-service firm with a team of lawyers who provide timely and efficient advice in all practice areas\",\"email\":\"contact@alcogal.com\",\"telephone\":\"+507 269-2620\",\"foundingDate\":\"1985-01-01\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Otras \u00c1reas de Pr\u00e1ctica | Alem\u00e1n, Cordero, Galindo &amp; Lee","description":"Immigration, Intellectual property, International trade, Labor Maritime and port facilities, Telecommunications, Insurance and more","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alcogal.com\/es\/otras-areas-de-practica\/","og_locale":"es_ES","og_type":"article","og_title":"Otras \u00c1reas de Pr\u00e1ctica","og_description":"Immigration, Intellectual property, International trade, Labor Maritime and port facilities, Telecommunications, Insurance and more","og_url":"https:\/\/alcogal.com\/es\/otras-areas-de-practica\/","og_site_name":"Alem\u00e1n, Cordero, Galindo &amp; Lee","article_publisher":"https:\/\/www.facebook.com\/AlcogalAbogados\/","article_modified_time":"2022-03-03T03:33:08+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/alcogal.com\/wp-content\/uploads\/2026\/02\/alcogal-new-og.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@alcogalabogados","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alcogal.com\/es\/otras-areas-de-practica\/","url":"https:\/\/alcogal.com\/es\/otras-areas-de-practica\/","name":"Otras \u00c1reas de Pr\u00e1ctica | Alem\u00e1n, Cordero, Galindo &amp; Lee","isPartOf":{"@id":"https:\/\/alcogal.com\/es\/#website"},"datePublished":"2021-09-09T04:42:07+00:00","dateModified":"2022-03-03T03:33:08+00:00","description":"Immigration, Intellectual property, International trade, Labor Maritime and port facilities, Telecommunications, Insurance and more","breadcrumb":{"@id":"https:\/\/alcogal.com\/es\/otras-areas-de-practica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alcogal.com\/es\/otras-areas-de-practica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alcogal.com\/es\/otras-areas-de-practica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alcogal.com\/es\/"},{"@type":"ListItem","position":2,"name":"Otras \u00c1reas de Pr\u00e1ctica"}]},{"@type":"WebSite","@id":"https:\/\/alcogal.com\/es\/#website","url":"https:\/\/alcogal.com\/es\/","name":"Alem\u00e1n Cordero Galindo & Lee","description":"Firma de Abogados en Panam\u00e1","publisher":{"@id":"https:\/\/alcogal.com\/es\/#organization"},"alternateName":"Alcogal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alcogal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/alcogal.com\/es\/#organization","name":"Aleman, Cordero, Galindo & Lee","alternateName":"Alcogal","url":"https:\/\/alcogal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/alcogal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/04\/logo-alcogal.png","contentUrl":"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/04\/logo-alcogal.png","width":696,"height":696,"caption":"Aleman, Cordero, Galindo & Lee"},"image":{"@id":"https:\/\/alcogal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AlcogalAbogados\/","https:\/\/x.com\/alcogalabogados","https:\/\/www.linkedin.com\/company\/alcogal\/","https:\/\/www.instagram.com\/alcogalabogados\/"],"description":"Since our foundation in 1985, we have established ourselves as one of Panama\u2019s most prestigious law firms. We are a full-service firm with a team of lawyers who provide timely and efficient advice in all practice areas","email":"contact@alcogal.com","telephone":"+507 269-2620","foundingDate":"1985-01-01"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/pages\/12009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/comments?post=12009"}],"version-history":[{"count":0,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/pages\/12009\/revisions"}],"wp:attachment":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/media?parent=12009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}