{"id":23447,"date":"2026-03-19T14:47:58","date_gmt":"2026-03-19T19:47:58","guid":{"rendered":"https:\/\/alcogal.com\/attorneys\/raul-borrell-azcarraga\/"},"modified":"2026-04-28T15:30:49","modified_gmt":"2026-04-28T20:30:49","slug":"raul-borrell-azcarraga","status":"publish","type":"attorney","link":"https:\/\/alcogal.com\/es\/attorneys\/raul-borrell-azcarraga\/","title":{"rendered":"Ra\u00fal Borrell Azc\u00e1rraga"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","footnotes":""},"practice_area":[],"class_list":["post-23447","attorney","type-attorney","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ra\u00fal Borrell Azc\u00e1rraga | Alem\u00e1n, Cordero, Galindo &amp; Lee<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alcogal.com\/es\/attorneys\/raul-borrell-azcarraga\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ra\u00fal Borrell Azc\u00e1rraga\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alcogal.com\/es\/attorneys\/raul-borrell-azcarraga\/\" \/>\n<meta property=\"og:site_name\" content=\"Alem\u00e1n, Cordero, Galindo &amp; Lee\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AlcogalAbogados\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T20:30:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/04\/logo-alcogal.png\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"696\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@alcogalabogados\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/attorneys\\\/raul-borrell-azcarraga\\\/\",\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/attorneys\\\/raul-borrell-azcarraga\\\/\",\"name\":\"Ra\u00fal Borrell Azc\u00e1rraga | Alem\u00e1n, Cordero, Galindo &amp; Lee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#website\"},\"datePublished\":\"2026-03-19T19:47:58+00:00\",\"dateModified\":\"2026-04-28T20:30:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/attorneys\\\/raul-borrell-azcarraga\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alcogal.com\\\/es\\\/attorneys\\\/raul-borrell-azcarraga\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/attorneys\\\/raul-borrell-azcarraga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alcogal.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attorneys\",\"item\":\"https:\\\/\\\/alcogal.com\\\/es\\\/attorneys\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ra\u00fal Borrell Azc\u00e1rraga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/\",\"name\":\"Alem\u00e1n Cordero Galindo & Lee\",\"description\":\"Firma de Abogados en Panam\u00e1\",\"publisher\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#organization\"},\"alternateName\":\"Alcogal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alcogal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#organization\",\"name\":\"Aleman, Cordero, Galindo & Lee\",\"alternateName\":\"Alcogal\",\"url\":\"https:\\\/\\\/alcogal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-alcogal.png\",\"contentUrl\":\"https:\\\/\\\/alcogal.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-alcogal.png\",\"width\":696,\"height\":696,\"caption\":\"Aleman, Cordero, Galindo & Lee\"},\"image\":{\"@id\":\"https:\\\/\\\/alcogal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AlcogalAbogados\\\/\",\"https:\\\/\\\/x.com\\\/alcogalabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/alcogal\\\/\",\"https:\\\/\\\/www.instagram.com\\\/alcogalabogados\\\/\"],\"description\":\"Since our foundation in 1985, we have established ourselves as one of Panama\u2019s most prestigious law firms. We are a full-service firm with a team of lawyers who provide timely and efficient advice in all practice areas\",\"email\":\"contact@alcogal.com\",\"telephone\":\"+507 269-2620\",\"foundingDate\":\"1985-01-01\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ra\u00fal Borrell Azc\u00e1rraga | Alem\u00e1n, Cordero, Galindo &amp; Lee","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alcogal.com\/es\/attorneys\/raul-borrell-azcarraga\/","og_locale":"es_ES","og_type":"article","og_title":"Ra\u00fal Borrell Azc\u00e1rraga","og_url":"https:\/\/alcogal.com\/es\/attorneys\/raul-borrell-azcarraga\/","og_site_name":"Alem\u00e1n, Cordero, Galindo &amp; Lee","article_publisher":"https:\/\/www.facebook.com\/AlcogalAbogados\/","article_modified_time":"2026-04-28T20:30:49+00:00","og_image":[{"width":696,"height":696,"url":"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/04\/logo-alcogal.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@alcogalabogados","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alcogal.com\/es\/attorneys\/raul-borrell-azcarraga\/","url":"https:\/\/alcogal.com\/es\/attorneys\/raul-borrell-azcarraga\/","name":"Ra\u00fal Borrell Azc\u00e1rraga | Alem\u00e1n, Cordero, Galindo &amp; Lee","isPartOf":{"@id":"https:\/\/alcogal.com\/es\/#website"},"datePublished":"2026-03-19T19:47:58+00:00","dateModified":"2026-04-28T20:30:49+00:00","breadcrumb":{"@id":"https:\/\/alcogal.com\/es\/attorneys\/raul-borrell-azcarraga\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alcogal.com\/es\/attorneys\/raul-borrell-azcarraga\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alcogal.com\/es\/attorneys\/raul-borrell-azcarraga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alcogal.com\/es\/"},{"@type":"ListItem","position":2,"name":"Attorneys","item":"https:\/\/alcogal.com\/es\/attorneys\/"},{"@type":"ListItem","position":3,"name":"Ra\u00fal Borrell Azc\u00e1rraga"}]},{"@type":"WebSite","@id":"https:\/\/alcogal.com\/es\/#website","url":"https:\/\/alcogal.com\/es\/","name":"Alem\u00e1n Cordero Galindo & Lee","description":"Firma de Abogados en Panam\u00e1","publisher":{"@id":"https:\/\/alcogal.com\/es\/#organization"},"alternateName":"Alcogal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alcogal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/alcogal.com\/es\/#organization","name":"Aleman, Cordero, Galindo & Lee","alternateName":"Alcogal","url":"https:\/\/alcogal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/alcogal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/04\/logo-alcogal.png","contentUrl":"https:\/\/alcogal.com\/wp-content\/uploads\/2025\/04\/logo-alcogal.png","width":696,"height":696,"caption":"Aleman, Cordero, Galindo & Lee"},"image":{"@id":"https:\/\/alcogal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AlcogalAbogados\/","https:\/\/x.com\/alcogalabogados","https:\/\/www.linkedin.com\/company\/alcogal\/","https:\/\/www.instagram.com\/alcogalabogados\/"],"description":"Since our foundation in 1985, we have established ourselves as one of Panama\u2019s most prestigious law firms. We are a full-service firm with a team of lawyers who provide timely and efficient advice in all practice areas","email":"contact@alcogal.com","telephone":"+507 269-2620","foundingDate":"1985-01-01"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/attorney\/23447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/attorney"}],"about":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/types\/attorney"}],"version-history":[{"count":2,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/attorney\/23447\/revisions"}],"predecessor-version":[{"id":25602,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/attorney\/23447\/revisions\/25602"}],"wp:attachment":[{"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/media?parent=23447"}],"wp:term":[{"taxonomy":"practice_area","embeddable":true,"href":"https:\/\/alcogal.com\/es\/wp-json\/wp\/v2\/practice_area?post=23447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}